{"id":43693,"date":"2022-06-01T09:21:06","date_gmt":"2022-06-01T09:21:06","guid":{"rendered":"https:\/\/www.zbw-mediatalk.eu\/?p=43693"},"modified":"2024-11-15T08:12:59","modified_gmt":"2024-11-15T08:12:59","slug":"horizon-report-2022-trends-wie-hybrides-lernen-mikrozertifikate-und-kuenstliche-intelligenz-verstaerken-sich","status":"publish","type":"post","link":"https:\/\/www.zbw-mediatalk.eu\/de\/2022\/06\/horizon-report-2022-trends-wie-hybrides-lernen-mikrozertifikate-und-kuenstliche-intelligenz-verstaerken-sich\/","title":{"rendered":"Horizon Report 2022: Trends wie hybrides Lernen, Mikrozertifikate und k\u00fcnstliche Intelligenz verst\u00e4rken sich"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:1402,&quot;href&quot;:&quot;https:\\\/\\\/library.educause.edu\\\/resources\\\/2022\\\/4\\\/2022-educause-horizon-report-teaching-and-learning-edition&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1403,&quot;href&quot;:&quot;https:\\\/\\\/www.opb.org\\\/article\\\/2021\\\/11\\\/17\\\/portland-state-university-experiments-with-attend-anywhere-model&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260313185955\\\/https:\\\/\\\/www.opb.org\\\/article\\\/2021\\\/11\\\/17\\\/portland-state-university-experiments-with-attend-anywhere-model\\\/&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.opb.org\\\/article\\\/2021\\\/11\\\/17\\\/portland-state-university-experiments-with-attend-anywhere-model\\\/&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1404,&quot;href&quot;:&quot;https:\\\/\\\/www.planetaryhealthalliance.org\\\/education-framework&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20240527055108\\\/https:\\\/\\\/www.planetaryhealthalliance.org\\\/education-framework&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.planetaryhealthalliance.org\\\/resources\\\/education-framework\\\/&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1405,&quot;href&quot;:&quot;https:\\\/\\\/sdgs.un.org\\\/goals&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260313190131\\\/https:\\\/\\\/sdgs.un.org\\\/goals&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-18 05:02:23&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-03-29 16:56:27&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-04 19:33:21&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-04 19:33:21&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1406,&quot;href&quot;:&quot;https:\\\/\\\/www.educause.edu\\\/research-and-publications\\\/research\\\/top-10-it-issues-technologies-and-trends&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1407,&quot;href&quot;:&quot;https:\\\/\\\/www.scil.ch\\\/2022\\\/05\\\/07\\\/educause-horizon-report-2022&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20230401133654\\\/https:\\\/\\\/www.scil.ch\\\/2022\\\/05\\\/07\\\/educause-horizon-report-2022\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 18:15:26&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-13 18:15:26&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1139,&quot;href&quot;:&quot;https:\\\/\\\/www.wirtschaftsdienst.eu&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260301124656\\\/https:\\\/\\\/www.wirtschaftsdienst.eu\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 16:08:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-18 02:06:51&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-22 09:02:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-26 09:48:34&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-30 03:27:04&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-02 08:50:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-06 03:55:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-10 21:33:03&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-15 10:39:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-19 07:57:51&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-22 21:55:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-30 00:29:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-07 11:46:43&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-07 11:46:43&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1140,&quot;href&quot;:&quot;https:\\\/\\\/de.linkedin.com\\\/in\\\/claudia-sittner-708951206&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1141,&quot;href&quot;:&quot;https:\\\/\\\/twitter.com\\\/ClaudiaSittner&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/x.com\\\/ClaudiaSittner&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1142,&quot;href&quot;:&quot;https:\\\/\\\/www.xing.com\\\/profile\\\/Claudia_Sittner&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/login.xing.com\\\/?locale=en&amp;dest_url=https%3A%2F%2Fwww.xing.com%2Fprofile%2FClaudia_Sittner&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:4733,&quot;href&quot;:&quot;https:\\\/\\\/www.zbw.eu\\\/de\\\/ueber-zbw\\\/profil\\\/mitarbeiterprofile\\\/profil-birgit-fingerle&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:13,&quot;href&quot;:&quot;https:\\\/\\\/openeconomics.zbw.eu&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260313063826\\\/https:\\\/\\\/openeconomics.zbw.eu\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 10:21:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-17 11:06:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-20 13:53:23&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-24 00:46:44&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-27 06:50:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-30 09:20:09&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-02 10:37:33&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-06 03:55:21&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-09 06:09:18&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-13 06:47:07&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-16 07:46:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-19 22:07:40&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-23 10:44:23&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-30 21:10:11&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-07 22:09:47&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-07 22:09:47&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:14,&quot;href&quot;:&quot;https:\\\/\\\/de.linkedin.com\\\/in\\\/birgit-inken-fingerle&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:15,&quot;href&quot;:&quot;https:\\\/\\\/www.northerncards.de&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p><b>von Claudia Sittner und Birgit Fingerle<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1.jpg\" alt=\"\" width=\"386\" height=\"200\" class=\"aligncenter size-full wp-image-43793\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1.jpg 772w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-300x155.jpg 300w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-150x78.jpg 150w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-768x398.jpg 768w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-680x352.jpg 680w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-500x259.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-400x207.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-250x130.jpg 250w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-200x104.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-100x52.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-76x39.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2022\/06\/2-Autoren-rundweiss-792x400-1-50x26.jpg 50w\" sizes=\"auto, (max-width: 386px) 100vw, 386px\" \/><\/p>\n<p>Der <a href=\"https:\/\/library.educause.edu\/resources\/2022\/4\/2022-educause-horizon-report-teaching-and-learning-edition\" target=\"_blank\" rel=\"noopener\">2022 EDUCAUSE Horizon Report Teaching and Learning Edition <\/a> wurde Mitte April 2022 ver\u00f6ffentlicht. Er besch\u00e4ftigt sich damit, welche Trends, Technologien und Praktiken die Lehre und das Lernen an Hochschulen in Zukunft ma\u00dfgeblich beeinflussen werden. Wie seine Vorg\u00e4nger spielt der Bericht anhand von vier unterschiedlichen Szenarien durch, wie die Zukunft der Hochschulbildung aussehen k\u00f6nnte. <\/p>\n<p>Wir fassen einige f\u00fcr wissenschaftliche Bibliotheken und Informationsinfrastruktureinrichtungen interessante Trends daraus zusammen.<\/p>\n<h2>Hybrides Lernern: Gekommen, um zu bleiben<\/h2>\n<p>Nach rund zwei Jahren Corona-Pandemie haben wohl die meisten eingesehen, dass es keine R\u00fcckkehr zur Vor-Corona-Normalit\u00e4t geben wird; Online- und hybrides Lernen hei\u00dft die neue Normalit\u00e4t. Als Trend sieht der Horizon Report eine Fortf\u00fchrung von synchronen und asynchronen Lernerfahrungen gepaart mit einer minimalen Anwesenheitspflicht auf dem Campus. Daf\u00fcr w\u00fcrden nun \u201enachhaltigere und evidenzbasierte Modelle f\u00fcr hybrides und Online-Lehren und -Lernen\u201c gebraucht, hei\u00dft es im Horizon Report (S. 7). Diese l\u00f6sten nun die am Beginn der Pandemie eilig gestrickten Notfallpl\u00e4ne sukzessive ab und sollten durch neu entwickelte, solide Hybrid- und Online-P\u00e4dagogik sowie eine Investition in zus\u00e4tzliches Personal und in Dienstleistungen flankiert werden. Hochschuleinrichtungen m\u00fcssten sich auch darauf konzentrieren, Studierende fit f\u00fcr die Online-Lernerfahrungen zu machen. Hier k\u00f6nnen sicher auch wissenschaftliche Bibliotheken ihren Teil beitragen. Das neue Motto laute: Bildung f\u00fcr jede:n von \u00fcberall.<br \/>\n<b>Beispiel:<\/b> <a href=\"https:\/\/www.opb.org\/article\/2021\/11\/17\/portland-state-university-experiments-with-attend-anywhere-model\/\" target=\"_blank\" rel=\"noopener\">Attend-Anywhere-Modell<\/a>, Portland, USA<\/p>\n<h2>Mikrozertifikate gewinnen gegen\u00fcber klassischen Universit\u00e4tsabschl\u00fcssen<\/h2>\n<p>Lebenslanges und passgenaues Lernen wird wichtiger im Kontrast zu klassischen, langwierigen Abschl\u00fcssen, hei\u00dft es im Horizon Report. Daf\u00fcr eigneten sich sowohl Microcredentialing als auch Online-\/Hybridbildung besonders. Bibliotheken und digitale Infrastruktureinrichtungen sollten deshalb den praktischeren, personalisierten und kompetenzbasierten Kursen und Mikrozertifikaten mehr Aufmerksamkeit schenken, die laut Horizon Report potenziell attraktivere M\u00f6glichkeiten f\u00fcr den beruflichen Aufstieg b\u00f6ten als das traditionelle Hochschulstudium. Bibliotheken k\u00f6nnten beispielsweise \u00fcberlegen, selbst entsprechende Kurse anzubieten, um mit ihren Angeboten sichtbarer zu werden, und den gro\u00dfen Tech-Konzernen nicht alleine das Feld zu \u00fcberlassen. <\/p>\n<p>Hinzu komme, dass viele Menschen aufgrund von in der Pandemie erlebten signifikanten finanziellen Einbu\u00dfen nun noch intensiver abw\u00e4gen, ob sich ein klassischer Hochschulabschluss f\u00fcr sie auszahle. Mikrozertifikate, insbesondere kostenlose von Einrichtungen wie Bibliotheken, gewinnen dabei an Attraktivit\u00e4t. <\/p>\n<p><b>Weiterlesen:<\/b><\/p>\n<ul>\n<li> <a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2022\/03\/open-badges-sinnvoller-leistungsnachweis-fuer-die-weiterbildung-in-bibliotheken\/ \" >Open Badges: Sinnvoller Leistungsnachweis f\u00fcr die Weiterbildung in Bibliotheken?<\/a> <\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2020\/09\/digitale-badges-informationskompetenz-clever-nachweisen\/\" >Digitale Badges: Informationskompetenz clever nachweisen<\/a><\/li>\n<\/ul>\n<h2>K\u00fcnstliche Intelligenz: Lernanalyse und Lerntools<\/h2>\n<p>Auch wenn sie oft noch in den Kinderschuhen stecke, spielt die Anwendung von k\u00fcnstlicher Intelligenz (KI) im diesj\u00e4hrigen Horizon Report gleich in zweierlei Hinsicht eine Rolle: in Bezug auf die Lernanalyse und auf Lerntools. In Bezug auf die Lernanalyse w\u00fcrden Institutionen KI vor allem nutzen, um auf der Basis vorhandener Daten den Lernerfolg von Lernenden zu f\u00f6rdern. Bei den Lerntools sind es die Lernenden selbst, die diese nutzen und so ihre Lernerfahrungen an den Universit\u00e4ten verbessern. <\/p>\n<p>Der pandemiebedingte digitale Schwenk habe auch eine gro\u00dfe Menge an digitalen Daten mit sich gebracht. Das bedeutet auch f\u00fcr wissenschaftliche Bibliotheken, sich intensiver mit dem Potenzial erzeugter Daten auseinanderzusetzen und ihren Nutzer:innen und Mitarbeiter:innen damit letztendlich eine verbesserte Lern- und Arbeitserfahrung zu bieten.<\/p>\n<p>Eine Herausforderung hierbei seien Datensilos einzelner Abteilungen, Bereiche oder Institute. Sie sollten st\u00e4rker integriert werden, um das Nutzungserlebnis zu verbessern und betriebliche Effizienz zu f\u00f6rdern. Trotz des gro\u00dfen Potenzials von KI gebe es auch einige Risiken zu bedenken, etwa dass KI-Systeme h\u00e4ufig bestehende Vorurteile (biases) \u00fcbernehmen und damit bestimmte Nutzer:innengruppen vorziehen. So w\u00fcrden Ungleichheiten verst\u00e4rkt. Au\u00dferdem m\u00fcsse transparent kommuniziert werden, welche Daten zu welchem Zweck gesammelt w\u00fcrden, damit das Vertrauen der Nutzer:innen in die Institutionen nicht verloren ginge. <\/p>\n<p><b>Weiterlesen:<\/b> <\/p>\n<ul>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2022\/03\/diskriminierung-durch-ki-inwiefern-bibliotheken-betroffen-sind-und-wie-mitarbeitende-das-richtige-mindset-finden\/\" >Diskriminierung durch KI: Inwiefern Bibliotheken betroffen sind und wie Mitarbeitende das richtige Mindset finden<\/a><\/li>\n<\/ul>\n<h2>Datenspuren erfordern kritischen Umgang mit Medien<\/h2>\n<p>Angesichts der wachsenden Datenmengen hinterlie\u00dfen Nutzer:innen von Infrastruktureinrichtungen vermehrt Datenspuren im Netz, etwa in Clouds oder in sozialen Netzwerken. Umso wichtiger sei es, sie mit ausreichend Informationskompetenz und einem medienkritischen Bewusstsein auszustatten, um beispielsweise Fake News, unseri\u00f6se Konferenzen und Predatory Jounals zu erkennen. Hier kommt wissenschaftlichen Bibliotheken mehr denn je eine wichtige Rolle zu, entsprechende Kurse und weitere Unterst\u00fctzung anzubieten.<\/p>\n<h2>Nachhaltige Praktiken st\u00e4rken und den Klima-Fu\u00dfabdruck verringern<\/h2>\n<p>F\u00fcr alle Hochschuleinrichtungen w\u00fcrden Umweltaspekte zunehmend auch im eigenen Handeln relevant. Es werde darum gehen, den eigenen Klima-Fu\u00dfabdruck vor Ort zu verringern und mit gutem Beispiel voranzugehen. Hierbei k\u00f6nnen Bibliotheken den Blick auf das durch die Pandemie bedingte nachhaltig ge\u00e4nderte Verhalten und neue Bed\u00fcrfnisse der Nutzer:innen und Mitarbeiter:innen richten. Anhaltspunkte k\u00f6nnten beispielsweise das <a href=\"https:\/\/www.planetaryhealthalliance.org\/education-framework\" target=\"_blank\" rel=\"noopener\">\u201ePlanetary Health Education Framework\u201c<\/a> und die <a href=\"https:\/\/sdgs.un.org\/goals\" target=\"_blank\" rel=\"noopener\">17 Ziele f\u00fcr nachhaltige Entwicklung<\/a> der Vereinten Nationen liefern. Vielleicht ein guter Zeitpunkt f\u00fcr wissenschaftliche Bibliotheken, sich zu \u00fcberlegen, wie sie nachhaltiger werden und umweltfreundliche Praktiken st\u00e4rken k\u00f6nnen? <\/p>\n<h2>Behauptung gegen politische Einflussnahmen<\/h2>\n<p>In Zeiten von mancherorts zunehmendem Nationalismus und Populismus gepaart mit globalen Unsicherheiten t\u00e4ten Bildungseinrichtungen gut daran, ihre Unabh\u00e4ngigkeit zu wahren. Aufgrund ihrer ben\u00f6tigten Finanzierung k\u00f6nnten sie sich politischen Anliegen aber nicht immer g\u00e4nzlich entziehen. \u201eIn diesen F\u00e4llen m\u00fcssen die Institutionen darauf vorbereitet sein, \u00fcberzeugende Beweise f\u00fcr die Vorteile der von ihnen angebotenen Bildung und Ausbildung vorzulegen und den Bed\u00fcrfnissen der zunehmend belasteten und abgelenkten Studenten und Familien gerecht zu werden\u201c (S. 13). Angesichts knapper werdender finanzieller Ressourcen k\u00f6nnten hier auch wissenschaftliche Bibliotheken st\u00e4rker in den Fokus geraten.<\/p>\n\n<div style=\"font-size: 10pt; line-height: 1.5em;\">\n<a href=\"https:\/\/library.educause.edu\/resources\/2022\/4\/2022-educause-horizon-report-teaching-and-learning-edition\" target=\"_blank\" rel=\"noopener\">2022 EDUCAUSE Horizon Report Teaching and Learning Edition <\/a><\/div>\n<p><b>Das k\u00f6nnte Sie auch interessieren:<\/b><\/p>\n<ul>\n<li>Die wichtigsten <a href=\"https:\/\/www.educause.edu\/research-and-publications\/research\/top-10-it-issues-technologies-and-trends\" target=\"_blank\" rel=\"noopener\">IT-Themen, Trends und Technologien<\/a> von EDUCAUSE <\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2021\/07\/horizon-report-2021-hybrides-lernen-mikrozertifikate-und-online-qualitaetssicherung-im-fokus\/ \" >Horizon Report 2021: Hybrides Lernen, Mikrozertifikate und Online-Qualit\u00e4tssicherung im Fokus<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2020\/03\/horizont-bericht-2020-ai-xr-und-oer-setzen-sich-langsam-in-der-hochschulbildung-durch\/\" >Horizon-Bericht 2020: AI, XR und OER setzen sich langsam in der Hochschulbildung durch<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2019\/05\/horizon-report-2019-wie-neue-technologien-lernen-und-lehre-innovieren\/\" >Horizon Report 2019: Wie neue Technologien Lernen und Lehre innovieren<\/a><\/li>\n<li><a href=\"https:\/\/www.scil.ch\/2022\/05\/07\/educause-horizon-report-2022\/\" target=\"_blank\" rel=\"noopener\">Zusammenfassung<\/a> EDUCAUSE Horizon Report 2022<\/li>\n<li><a href=\" https:\/\/www.zbw-mediatalk.eu\/de\/2020\/09\/digitale-badges-informationskompetenz-clever-nachweisen\/ \" > Digitale Badges: Informationskompetenz clever nachweisen <\/a><\/li>\n<li> <a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2019\/06\/studie-hochschullandschaft-2030-oeffnung-durch-neue-studienmodelle\/ \" >Studie Hochschullandschaft 2030: \u00d6ffnung durch neue Studienmodelle <\/a><\/li>\n<\/ul>\n<div class='eckosc eckosc_contrast_block'><div class='eckosc_contrast_block_inner'>\n<p><b>\u00dcber die Autorinnen:<\/b><\/p>\n<p><b>Claudia Sittner<\/b> studierte Journalistik und Sprachen in Hamburg und London. Sie war lange Zeit Referentin beim von der ZBW herausgegebenen <a href=\"https:\/\/www.wirtschaftsdienst.eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Wirtschaftsdienst \u2013 Zeitschrift f\u00fcr Wirtschaftspolitik<\/a> und ist heute Redakteurin des Blogs ZBW MediaTalk. Sie ist freiberufliche Reise-Bloggerin, Rednerin und Autorin. Sie ist auch auf <a href=\"https:\/\/de.linkedin.com\/in\/claudia-sittner-708951206\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, <a href=\"https:\/\/twitter.com\/ClaudiaSittner\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> und <a href=\"https:\/\/www.xing.com\/profile\/Claudia_Sittner\/\" target=\"_blank\" rel=\"noopener\">Xing<\/a> zu finden.<br \/>\nPortr\u00e4t: Claudia Sittner&copy;<\/p>\n<p><b><a href=\"https:\/\/www.zbw.eu\/de\/ueber-zbw\/profil\/mitarbeiterprofile\/profil-birgit-fingerle\" target=\"_blank\" rel=\"noopener\">Birgit Fingerle<\/a><\/b> ist Diplom-\u00d6konomin und besch\u00e4ftigt sich in der ZBW unter anderem mit Innovationsmanagement, Open Innovation, Open Science und aktuell insbesondere mit dem <a href=\"https:\/\/openeconomics.zbw.eu\/\" target=\"_blank\" rel=\"noopener\">&#8220;Open Economics Guide&#8221;<\/a>. Birgit Fingerle ist auch auf <a href=\"https:\/\/de.linkedin.com\/in\/birgit-inken-fingerle\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a> zu finden.<br \/>\nPortr\u00e4t, Fotograf: <a href=\"https:\/\/www.northerncards.de\/\" target=\"_blank\" rel=\"noopener\">Northerncards<\/a>&copy;<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit hybridem Lernen, Mikrozertifikaten und k\u00fcnstlicher Intelligenz verst\u00e4rken sich laut Horizon Report einige aus den Vorjahren bereits bekannte Trends im Hochschulbereich. Wie dies geschieht und welche weiteren Trends besonders relevant erscheinen, berichten wir im Blogpost.  <\/p>\n","protected":false},"author":4,"featured_media":43703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_has_post_settings":[],"footnotes":""},"categories":[1147],"tags":[1423,2472,2406,1197,2473,1741,1775],"hashtags":[],"class_list":["post-43693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-open-science-de","tag-horizon-report-de","tag-hybrides-lernen","tag-ki","tag-kuenstliche-intelligenz","tag-mikrozertifikate","tag-technologien","tag-trends-de"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/43693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/comments?post=43693"}],"version-history":[{"count":6,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/43693\/revisions"}],"predecessor-version":[{"id":47992,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/43693\/revisions\/47992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media\/43703"}],"wp:attachment":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media?parent=43693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/categories?post=43693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/tags?post=43693"},{"taxonomy":"hashtags","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/hashtags?post=43693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}