{"id":38087,"date":"2021-01-27T12:55:12","date_gmt":"2021-01-27T12:55:12","guid":{"rendered":"https:\/\/www.zbw-mediatalk.eu\/?p=38087"},"modified":"2024-06-26T09:53:34","modified_gmt":"2024-06-26T09:53:34","slug":"wissenschaftsbarometer-2020-handlungsfelder-fuer-open-science","status":"publish","type":"post","link":"https:\/\/www.zbw-mediatalk.eu\/de\/2021\/01\/wissenschaftsbarometer-2020-handlungsfelder-fuer-open-science\/","title":{"rendered":"Wissenschaftsbarometer 2020: Handlungsfelder f\u00fcr Open Science?"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:5042,&quot;href&quot;:&quot;https:\\\/\\\/www.wissenschaft-im-dialog.de\\\/projekte\\\/wissenschaftsbarometer&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260310132944\\\/https:\\\/\\\/wissenschaft-im-dialog.de\\\/projekte\\\/wissenschaftsbarometer\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-24 14:32:40&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-10 19:40:17&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-10 19:40:17&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:2276,&quot;href&quot;:&quot;https:\\\/\\\/www.wissenschaft-im-dialog.de\\\/fileadmin\\\/user_upload\\\/Projekte\\\/Wissenschaftsbarometer\\\/Dokumente_20\\\/WiD-Wissenschaftsbarometer_2020_Broschuere_final.pdf&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/wissenschaft-im-dialog.de\\\/fileadmin\\\/user_upload\\\/Projekte\\\/Wissenschaftsbarometer\\\/Dokumente_20\\\/WiD-Wissenschaftsbarometer_2020_Broschuere_final.pdf&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5043,&quot;href&quot;:&quot;https:\\\/\\\/www.creativecommons.org\\\/licenses\\\/by-nd\\\/4.0\\\/deed.de&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260318140128\\\/https:\\\/\\\/creativecommons.org\\\/licenses\\\/by-nd\\\/4.0\\\/deed.de&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/creativecommons.org\\\/licenses\\\/by-nd\\\/4.0\\\/deed.de&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5044,&quot;href&quot;:&quot;https:\\\/\\\/www.wissenschaft-im-dialog.de&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260322010729\\\/https:\\\/\\\/wissenschaft-im-dialog.de\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-24 14:32:52&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-20 05:54:32&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-04 11:46:40&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-04 11:46:40&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5045,&quot;href&quot;:&quot;https:\\\/\\\/www.bosch-stiftung.de\\\/de\\\/projekt\\\/wissenschaftsbarometer-eine-repraesentative-bevoelkerungsumfrage-zu-wissenschaft-und&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260117183447\\\/https:\\\/\\\/www.bosch-stiftung.de\\\/de\\\/projekt\\\/wissenschaftsbarometer-eine-repraesentative-bevoelkerungsumfrage-zu-wissenschaft-und&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-24 14:33:46&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-24 14:33:46&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5046,&quot;href&quot;:&quot;https:\\\/\\\/www.fraunhofer.de\\\/de\\\/presse\\\/presseinformationen\\\/2020\\\/april\\\/fraunhofer-unterstuetzt-wissenschaftsbarometer-corona-spezial.html&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260324143943\\\/https:\\\/\\\/www.fraunhofer.de\\\/de\\\/presse\\\/presseinformationen\\\/2020\\\/april\\\/fraunhofer-unterstuetzt-wissenschaftsbarometer-corona-spezial.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:2281,&quot;href&quot;:&quot;https:\\\/\\\/www.wissenschaft-im-dialog.de\\\/projekte\\\/wissenschaftsbarometer\\\/wissenschaftsbarometer-2020&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/wissenschaft-im-dialog.de\\\/projekte\\\/wissenschaftsbarometer\\\/wissenschaftsbarometer-2020&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:2282,&quot;href&quot;:&quot;https:\\\/\\\/www.ndr.de\\\/fernsehen\\\/sendungen\\\/zapp\\\/Podcasts-Medien-Gewinner-der-Coronakrise,coronapodcasts100.html&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20210310151641\\\/https:\\\/\\\/www.ndr.de\\\/fernsehen\\\/sendungen\\\/zapp\\\/Podcasts-Medien-Gewinner-der-Coronakrise,coronapodcasts100.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 23:42:33&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-02 05:11:48&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-19 14:05:49&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-19 14:05:49&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:2283,&quot;href&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=DLLvIQxQwLs&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260314000953\\\/https:\\\/\\\/www.youtube.com\\\/watch?v=DLLvIQxQwLs&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-02 05:11:51&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-19 14:05:50&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-19 14:05:50&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5047,&quot;href&quot;:&quot;https:\\\/\\\/www.wissenschaft-im-dialog.de\\\/fileadmin\\\/user_upload\\\/Projekte\\\/Wissenschaftsbarometer\\\/Dokumente_20\\\/20_WiD_Fragebogen_Wissenschaftsbarometer2020_final.pdf&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/wissenschaft-im-dialog.de\\\/fileadmin\\\/user_upload\\\/Projekte\\\/Wissenschaftsbarometer\\\/Dokumente_20\\\/20_WiD_Fragebogen_Wissenschaftsbarometer2020_final.pdf&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:2286,&quot;href&quot;:&quot;https:\\\/\\\/www.wissenschaft-im-dialog.de\\\/fileadmin\\\/user_upload\\\/Projekte\\\/Wissenschaftsbarometer\\\/Dokumente_20\\\/20_WiD_Tabellenband_Wissenschaftsbarometer2020_final.pdf&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20240114054145\\\/https:\\\/\\\/www.wissenschaft-im-dialog.de\\\/fileadmin\\\/user_upload\\\/Projekte\\\/Wissenschaftsbarometer\\\/Dokumente_20\\\/20_WiD_Tabellenband_Wissenschaftsbarometer2020_final.pdf&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 23:43:29&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-02 05:11:53&quot;,&quot;http_code&quot;:404},{&quot;date&quot;:&quot;2026-04-19 14:05:53&quot;,&quot;http_code&quot;:404}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-19 14:05:53&quot;,&quot;http_code&quot;:404},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1139,&quot;href&quot;:&quot;https:\\\/\\\/www.wirtschaftsdienst.eu&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260301124656\\\/https:\\\/\\\/www.wirtschaftsdienst.eu\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 16:08:59&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-18 02:06:51&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-22 09:02:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-26 09:48:34&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-30 03:27:04&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-02 08:50:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-06 03:55:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-10 21:33:03&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-15 10:39:50&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-19 07:57:51&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-22 21:55:56&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-30 00:29:16&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-07 11:46:43&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-07 11:46:43&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1837,&quot;href&quot;:&quot;https:\\\/\\\/weltreize.com&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260208102136\\\/https:\\\/\\\/weltreize.com\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-13 21:20:25&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-23 18:00:57&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-03-31 05:24:03&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-10 21:33:02&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-17 08:17:41&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-21 01:14:54&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-01 18:14:05&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-12 20:11:44&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-12 20:11:44&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1140,&quot;href&quot;:&quot;https:\\\/\\\/de.linkedin.com\\\/in\\\/claudia-sittner-708951206&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1141,&quot;href&quot;:&quot;https:\\\/\\\/twitter.com\\\/ClaudiaSittner&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/x.com\\\/ClaudiaSittner&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:1142,&quot;href&quot;:&quot;https:\\\/\\\/www.xing.com\\\/profile\\\/Claudia_Sittner&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/login.xing.com\\\/?locale=en&amp;dest_url=https%3A%2F%2Fwww.xing.com%2Fprofile%2FClaudia_Sittner&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p><b>von Claudia Sittner<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2020\/12\/Sittner-Autor-rundweiss-200x200-1.jpg\" alt=\"\" width=\"200\" height=\"200\" class=\"aligncenter size-full wp-image-37768\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2020\/12\/Sittner-Autor-rundweiss-200x200-1.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2020\/12\/Sittner-Autor-rundweiss-200x200-1-150x150.jpg 150w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2020\/12\/Sittner-Autor-rundweiss-200x200-1-100x100.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2020\/12\/Sittner-Autor-rundweiss-200x200-1-76x76.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2020\/12\/Sittner-Autor-rundweiss-200x200-1-50x50.jpg 50w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>Das <a href=\"https:\/\/www.wissenschaft-im-dialog.de\/projekte\/wissenschaftsbarometer\/\" target=\"_blank\" rel=\"noopener\">Wissenschaftsbarometer<\/a> \u2013 nicht zu verwechseln mit dem <a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2020\/12\/barometer-fuer-die-wissenschaft-2019-20-neue-erkenntnisse-fuer-open-science\/\" target=\"_blank\" rel=\"noopener\">Barometer f\u00fcr die Wissenschaft<\/a> \u2013 ist eine repr\u00e4sentative Meinungsumfrage und betrachtet seit 2014 j\u00e4hrlich die <b>Einstellung der B\u00fcrger:innen in Deutschland gegen\u00fcber Wissenschaft und Forschung<\/b>. Aufgrund der Corona-Krise gab es im April und Mai 2020 zus\u00e4tzliche Befragungen (\u201eCorona Spezial\u201c). Letzten Monat wurden nun die Ergebnisse der letzten Befragung vom November 2020 vorgestellt. <\/p>\n\n<div style=\"font-size: 10pt; line-height: 1.5em;\"><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/fileadmin\/user_upload\/Projekte\/Wissenschaftsbarometer\/Dokumente_20\/WiD-Wissenschaftsbarometer_2020_Broschuere_final.pdf\" target=\"_blank\" rel=\"noopener\">Broschure Wissenschaftsbarometer<\/a> (PDF). Die Verwendung der Grafiken der Ergebnisse ist unter Nennung der Quelle &#8220;Wissenschaft im Dialog\/Kantar Emnid&#8221; m\u00f6glich. Die Grafiken laufen unter der Lizenz <a href=\"https:\/\/www.creativecommons.org\/licenses\/by-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"noopener\">[CC BY-ND 4.0]<\/a>, Anpassungen des Formats f\u00fcr redaktionelle Ver\u00f6ffentlichungen sind erlaubt. <\/div>\n<p>In Auftrag gegeben wird das Wissenschaftsbarometer von <a href=\"https:\/\/www.wissenschaft-im-dialog.de\/\" target=\"_blank\" rel=\"noopener\">Wissenschaft im Dialog<\/a> (WiD). Die gemeinn\u00fctzige Initiative setzt sich daf\u00fcr ein, den Dialog \u00fcber Wissenschaft und Forschung in Deutschland zu f\u00f6rdern und dabei m\u00f6glichst viele Menschen an der Diskussion zu beteiligen. Au\u00dferdem treibt WiD die Weiterentwicklung von Wissenschaftskommunikation und damit auch von Open Science voran. Gef\u00f6rdert wird die Befragung von der <a href=\"https:\/\/www.bosch-stiftung.de\/de\/projekt\/wissenschaftsbarometer-eine-repraesentative-bevoelkerungsumfrage-zu-wissenschaft-und\" target=\"_blank\" rel=\"noopener\">Robert Bosch Stiftung<\/a> und der <a href=\"https:\/\/www.fraunhofer.de\/de\/presse\/presseinformationen\/2020\/april\/fraunhofer-unterstuetzt-wissenschaftsbarometer-corona-spezial.html\" target=\"_blank\" rel=\"noopener\">Fraunhofer-Gesellschaft<\/a>.<\/p>\n<p>Befragt wurden in den Telefoninterviews rund 1.000 B\u00fcrger:innen ab 14 Jahren in Privathaushalten. Als Grundgesamtheit diente die deutschsprachige Wohnbev\u00f6lkerung. Wir haben uns die Ergebnisse des Wissenschaftsbarometers 2020 im Hinblick auf ihre Bedeutung f\u00fcr Open Science in Wissenschaft und Forschung angesehen und stellen interessante Erkenntnisse vor.<\/p>\n<h2>Interesse stabil, klassische Medien wichtigste Informationsquelle<\/h2>\n<p>Das Interesse an Wissenschaft und Forschung ist bei der Bev\u00f6lkerung mit 60% stabil und wird nur vom Interesse an lokalen Neuigkeiten (68%) \u00fcbertroffen. Das korrespondiert mit der Meinung von 59% der Befragten, die der Aussagen eher oder voll zustimmen, dass sie pers\u00f6nlich von Wissenschaft und Forschung profitieren.<\/p>\n<div id=\"attachment_38091\" style=\"width: 910px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38091\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse.jpg\" alt=\"\" width=\"900\" height=\"450\" class=\"size-full wp-image-38091\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse.jpg 900w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-300x150.jpg 300w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-150x75.jpg 150w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-768x384.jpg 768w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-860x430.jpg 860w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-680x340.jpg 680w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-500x250.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-400x200.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-250x125.jpg 250w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-200x100.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-100x50.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-76x38.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_Interesse-50x25.jpg 50w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><p id=\"caption-attachment-38091\" class=\"wp-caption-text\"><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/projekte\/wissenschaftsbarometer\/wissenschaftsbarometer-2020\/\" target=\"_blank\" rel=\"noopener\">Wissenschaftsbarometer 2020<\/a>. Die Verwendung der Grafiken der Ergebnisse ist unter Nennung der Quelle &#8220;Wissenschaft im Dialog\/Kantar Emnid&#8221; m\u00f6glich. Die Grafiken laufen unter der Lizenz <a href=\"https:\/\/www.creativecommons.org\/licenses\/by-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"noopener\">[CC BY-ND 4.0]<\/a>, Anpassungen des Formats f\u00fcr redaktionelle Ver\u00f6ffentlichungen sind erlaubt.<\/p><\/div>\n<p>Informiert wird sich vor allem (80% \u2013 gelegentlich bis sehr h\u00e4ufig) \u00fcber die klassischen Medien. Seltener \u00fcber Webauftritte von wissenschaftlichen Einrichtungen (43%), und nur in 29% der F\u00e4lle informieren sich Befragte \u00fcber Forschungsthemen in den sozialen Medien. Vor dem Hintergrund der Corona-Pandemie wurden dabei Online-Angebote der klassischen Nachrichtenmedien relevanter.<\/p>\n<p>F\u00fcr Wissenschaft und Forschung bedeutet das, dass es sich lohnen kann, mehr in Presse- und \u00d6ffentlichkeitsarbeit zu investieren, damit relevante wissenschaftliche Erkenntnisse von den klassischen Medien aufgegriffen werden und bei der Bev\u00f6lkerung ankommen k\u00f6nnen. Gerade f\u00fcr Institute, die sich f\u00fcr Open Science engagieren, scheint das ein guter Ansatzpunkt zu sein, damit ihre Inhalte und ihr Engagement st\u00e4rker wahrgenommen werden. Dazu passend sind auch ein Drittel der Befragten der Ansicht, Wissenschaftler:innen sollten mehr\/st\u00e4rker \u00fcber ihre Arbeit informieren.<\/p>\n<h2>Vertrauen h\u00f6her als in den Vorjahren, Tendenz im Corona-Jahr 2020 sinkend<\/h2>\n<p>Das Vertrauen in Wissenschaft und Forschung ist auch im November 2020 mit fast zwei Drittel (60% vertrauen eher sowie voll und ganz) recht hoch. In den Vorjahren lag dieser Wert jeweils um die 50%. Interessant ist hier, dass das Vertrauen in Wissenschaft und Forschung zu Beginn der Corona-Pandemie (Befragung April 2020) zun\u00e4chst stark \u2013 auf 77% \u2013 gestiegen ist: Im Vergleich zur Befragung von 2019 vertrauten viermal so viele Befragte \u201evoll und ganz\u201c. Bis zur Novemberbefragung halbierte sich dieser Wert allerdings fast wieder.<\/p>\n<div id=\"attachment_38093\" style=\"width: 910px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38093\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen.jpg\" alt=\"\" width=\"900\" height=\"450\" class=\"size-full wp-image-38093\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen.jpg 900w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-300x150.jpg 300w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-150x75.jpg 150w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-768x384.jpg 768w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-860x430.jpg 860w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-680x340.jpg 680w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-500x250.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-400x200.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-250x125.jpg 250w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-200x100.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-100x50.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-76x38.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20_Wiba_2020_GruendeVertrauen-50x25.jpg 50w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><p id=\"caption-attachment-38093\" class=\"wp-caption-text\"><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/projekte\/wissenschaftsbarometer\/wissenschaftsbarometer-2020\/\" target=\"_blank\" rel=\"noopener\">Wissenschaftsbarometer 2020<\/a>. Die Verwendung der Grafiken der Ergebnisse ist unter Nennung der Quelle &#8220;Wissenschaft im Dialog\/Kantar Emnid&#8221; m\u00f6glich. Die Grafiken laufen unter der Lizenz <a href=\"https:\/\/www.creativecommons.org\/licenses\/by-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"noopener\">[CC BY-ND 4.0]<\/a>, Anpassungen des Formats f\u00fcr redaktionelle Ver\u00f6ffentlichungen sind erlaubt.<\/p><\/div>\n<p>Das zeigt einen hohen Vertrauensvorschuss in Wissenschaft und Forschung zu Beginn der Pandemie und k\u00f6nnte auf eine Entt\u00e4uschung Vieler im zweiten Corona-Lockdown schlie\u00dfen lassen.<\/p>\n<div id=\"attachment_38100\" style=\"width: 910px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38100\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen.jpg\" alt=\"\" width=\"900\" height=\"450\" class=\"size-full wp-image-38100\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen.jpg 900w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-300x150.jpg 300w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-150x75.jpg 150w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-768x384.jpg 768w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-860x430.jpg 860w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-680x340.jpg 680w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-500x250.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-400x200.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-250x125.jpg 250w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-200x100.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-100x50.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-76x38.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-GruendeMisstrauen-50x25.jpg 50w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><p id=\"caption-attachment-38100\" class=\"wp-caption-text\"><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/projekte\/wissenschaftsbarometer\/wissenschaftsbarometer-2020\/\" target=\"_blank\" rel=\"noopener\">Wissenschaftsbarometer 2020<\/a>. Die Verwendung der Grafiken der Ergebnisse ist unter Nennung der Quelle &#8220;Wissenschaft im Dialog\/Kantar Emnid&#8221; m\u00f6glich. Die Grafiken laufen unter der Lizenz <a href=\"https:\/\/www.creativecommons.org\/licenses\/by-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"noopener\">[CC BY-ND 4.0]<\/a>, Anpassungen des Formats f\u00fcr redaktionelle Ver\u00f6ffentlichungen sind erlaubt.<\/p><\/div>\n<p>Als Gr\u00fcnde f\u00fcr die Glaubw\u00fcrdigkeit wurden Expertise, Integrit\u00e4t sowie Handeln im Interesse der  Allgemeinheit erhoben. Im Vergleich zum Vorjahr ist die Tendenz bei allen Gr\u00fcnden steigend. Die Gr\u00fcnde f\u00fcr Misstrauen liegen hingegen hier:<\/p>\n<ul>\n<li>Abh\u00e4ngigkeit von Geldgebenden (49% \u2013 stimmen eher sowie voll und ganz zu),<\/li>\n<li>Wissenschaftler:innen passen die Ergebnisse ihren Erwartungen an (25% \u2013 s.o.),<\/li>\n<li>machen h\u00e4ufig Fehler (16% \u2013 s.o.).<\/li>\n<\/ul>\n<p>Im Vergleich zum Vorjahr geht die Zustimmung f\u00fcr diese Gr\u00fcnde aber zum Teil stark zur\u00fcck. Damit korrespondiert der niedrigste Wert seit Beginn der Befragungsreihe in Bezug auf die Frage, ob die Menschen statt der Wissenschaft lieber ihren Gef\u00fchlen und ihrem Glauben trauen sollen (23% \u2013 stimmen eher sowie voll und ganz zu).<\/p>\n<p>F\u00fcr F\u00f6rderer:innen von Open Science k\u00f6nnte noch eine Rolle spielen, dass Vertrauen und Bildungsniveau hierbei korrelieren: Je h\u00f6her das formale Bildungsniveau, desto gr\u00f6\u00dfer das Vertrauen. Wenn man davon ausgeht, dass Wissenschaftskommunikation in den meisten F\u00e4llen vor allem Personen mit einer h\u00f6heren formalen Bildung erreicht, k\u00f6nnte das als positives Zeichen gewertet werden. Denn bei diesen Personen ist das Vertrauen in Wissenschaft und Forschung gro\u00df. Auf der anderen Seite hei\u00dft es allerdings auch, dass sich die Wissenschaftskommunikation noch mehr um Personen ohne h\u00f6here formale Bildung bem\u00fchen sollte, um das Vertrauen auch dieser Gruppe zu gewinnen.<\/p>\n<h2>Corona Spezial: Wissenschaft elementar wichtig, Kontroversen willkommen<\/h2>\n<p>Wenn es um Corona geht, vertraut die Bev\u00f6lkerung den Aussagen von \u00c4rzt:innen und medizinischem Personal am st\u00e4rksten (80% \u2013 vertrauen eher sowie voll und ganz), dicht gefolgt vom Vertrauen in die Aussagen von Wissenschaftler:innen (73% \u2013 vertrauen eher sowie voll und ganz). Allerdings vermuten auch einige (39% \u2013 stimmen eher sowie voll und ganz zu), dass Wissenschaftler:innen nicht alles sagen, was sie \u00fcber das Coronavirus wissen. Die gleiche Zahl an Befragten ist auch der Ansicht, dass es wichtig ist, Informationen \u00fcber das Virus von au\u00dferhalb der Wissenschaft zu beziehen.<\/p>\n<blockquote><p>\u201eDass weiterhin so viele Menschen der Wissenschaft vertrauen, zeigt, wie gut der Dialog zwischen Wissenschaft und Gesellschaft in der Pandemie funktioniert. Allerdings sollte uns eine relativ hohe Anzahl an Unentschiedenen und Zweifelnden beunruhigen: Die Wissenschaft muss sich noch st\u00e4rker \u00f6ffnen und auch mit denjenigen ins Gespr\u00e4ch kommen, die unsicher sind. Damit das gelingen kann, m\u00fcssen wir alle Forschenden dabei unterst\u00fctzen, ihr Wissen, ihre Werte und ihre Arbeitsweise zu vermitteln\u201c.<\/p>\n<p>\u2014 WiD-Gesch\u00e4ftsf\u00fchrer Markus Wei\u00dfkopf<\/p><\/blockquote>\n<p>Insgesamt w\u00fcnscht sich die \u00d6ffentlichkeit, dass politische Entscheidungen im Corona-Kontext auf wissenschaftlichen Erkenntnissen beruhen. Eine direkte Einmischung der Wissenschaftler:innen in die Politik ist allerdings nicht gew\u00fcnscht. Das sind alles in allem gute Neuigkeiten f\u00fcr Open-Science-Enthusiasten, bedeutet es doch, dass ihnen auch in Fragen zu Corona Glauben geschenkt wird und es sich also lohnt, weiterhin so offen wie m\u00f6glich zu forschen und die eigene Arbeit zu kommunizieren. Es zeigt auch, dass Open Science gerade durch seine Transparenz in der \u00d6ffentlichkeit punkten kann: Ergebnisse lassen sich offen nachvollziehen, und es gibt keine obligatorischen Mittelspersonen wie beispielsweise Journalist:innen, die Informationen filtern und bewerten.<\/p>\n<div id=\"attachment_38104\" style=\"width: 910px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-38104\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik.jpg\" alt=\"\" width=\"900\" height=\"450\" class=\"size-full wp-image-38104\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik.jpg 900w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-300x150.jpg 300w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-150x75.jpg 150w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-768x384.jpg 768w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-860x430.jpg 860w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-680x340.jpg 680w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-500x250.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-400x200.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-250x125.jpg 250w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-200x100.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-100x50.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-76x38.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2021\/01\/MT-20-Wiba-2020-WissundPolitik-50x25.jpg 50w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><p id=\"caption-attachment-38104\" class=\"wp-caption-text\"><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/projekte\/wissenschaftsbarometer\/wissenschaftsbarometer-2020\/\" target=\"_blank\" rel=\"noopener\">Wissenschaftsbarometer 2020<\/a>. Die Verwendung der Grafiken der Ergebnisse ist unter Nennung der Quelle &#8220;Wissenschaft im Dialog\/Kantar Emnid&#8221; m\u00f6glich. Die Grafiken laufen unter der Lizenz <a href=\"https:\/\/www.creativecommons.org\/licenses\/by-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"noopener\">[CC BY-ND 4.0]<\/a>, Anpassungen des Formats f\u00fcr redaktionelle Ver\u00f6ffentlichungen sind erlaubt.<\/p><\/div>\n<p>Zunehmend weniger Glauben wird hingegen den Aussagen von Politiker:innen und Journalist:innen geschenkt. Man k\u00f6nnte schlie\u00dfen, dass Forschende bei Corona-Themen gut beraten sind, Themen selbst an die \u00d6ffentlichkeit zu kommunizieren oder eine sehr enge Zusammenarbeit mit den klassischen Medien anzustreben. Als gute Option daf\u00fcr hat sich in der Corona-Krise das Format der <a href=\"https:\/\/www.ndr.de\/fernsehen\/sendungen\/zapp\/Podcasts-Medien-Gewinner-der-Coronakrise,coronapodcasts100.html\" target=\"_blank\" rel=\"noopener\">(wissenschaftlichen) Podcasts<\/a> etabliert, die im vergangenen Jahr stark an Zuh\u00f6rer:innen und Popularit\u00e4t gewonnen haben.<\/p>\n<p>Es besteht ein recht hohes Vertrauen dahingehend, dass Forschende deutlich kommunizieren, ob es sich bei ihren Aussagen um gesicherte Erkenntnisse oder offene Fragen zum Thema Corona handelt (46% \u2013 stimmen eher sowie voll und ganz zu; 40% unentschieden). Kontroversen zwischen Wissenschaftler:innen werden von mehr als zwei Dritteln der Befragten positiv und erkenntnisf\u00f6rdernd bewertet. F\u00fcr die Open-Science-Community ist das eine Best\u00e4tigung, setzt sie sich doch daf\u00fcr ein, Diskurse zu \u00f6ffnen und R\u00e4ume zu schaffen, damit diese transparent, \u00f6ffentlich und nachvollziehbar stattfinden k\u00f6nnen.<\/p>\n<p>Das ist umso wichtiger, als es auch Menschen gibt, \u201edie sich in der Corona-Pandemie lieber auf &#8220;den gesunden Menschenverstand&#8221; verlassen als auf wissenschaftliche Studien. Umso wichtiger ist es, wissenschaftliche Fakten und Handlungsempfehlungen \u00fcber vielf\u00e4ltige Formate zu vermitteln, um auch diejenigen zu erreichen, die unsicher sind und zweifeln\u201c, best\u00e4tigt Tina Stengele, kommissarische Leiterin des Bereichs Wissenschaft der Robert Bosch Stiftung, die das Wissenschaftsbarometer unterst\u00fctzt.<\/p>\n<h2>Fazit Wissenschaftsbarometer 2020: Wissenschaftskommunikation st\u00e4rken<\/h2>\n<p>Die Corona-Krise hat die schnelle Einsetzbarkeit und \u00dcberpr\u00fcfbarkeit wissenschaftlicher Ergebnisse erforderlicher gemacht als jemals zuvor. Damit ist die Wissenschaft auch st\u00e4rker in den Fokus der \u00d6ffentlichkeit ger\u00fcckt, deren Vertrauen in Forschende und deren Integrit\u00e4t auch laut der letzten Befragung des Wissenschaftsbarometers stark war. <\/p>\n<blockquote><p>\u201eEine entscheidende S\u00e4ule bei der St\u00e4rkung und dem Ausbau von Vertrauen ist die Zug\u00e4nglichkeit zu und die Nachvollziehbarkeit von Forschungsergebnissen. (\u2026) Dies best\u00e4rkt uns darin, dass es ein Erfolgsmodell ist, unumwunden Ergebnisse und Entwicklungen zu erkl\u00e4ren, sie einzuordnen und ihren Nutzen darzustellen \u2013 f\u00fcr Experten und Laien gleicherma\u00dfen\u201c.<\/p>\n<p>\u2014 Janis Eitner, Direktor Kommunikation der Fraunhofer-Gesellschaft<\/p><\/blockquote>\n<p>Aus Sicht von Open Science ist jetzt sicher immer noch ein guter Zeitpunkt, darauf zu dr\u00e4ngen, das Wissenschaftssystem in all seinen Teilprozessen noch offener zu machen und verst\u00e4rkt auf eine professionelle Wissenschaftskommunikation, auf eigene Kan\u00e4le wie Podcasts oder auf eine stabile Zusammenarbeit mit den klassischen Medien zu setzen. Die Verhandlungsposition f\u00fcr mehr Open Science ist gerade g\u00fcnstig und die Erfahrungen aus der Pandemie haben f\u00fcr jede:n unmissverst\u00e4ndlich verdeutlicht, wie wichtig ein offeneres \u00d6kosystem des freien Wissens in Zeiten globaler Krisen ist und sein wird.<\/p>\n<p><b>Das k\u00f6nnte Sie auch interessieren:<\/b><\/p>\n<ul>\n<li><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/projekte\/wissenschaftsbarometer\/\" target=\"_blank\" rel=\"noopener\">Wissenschaftsbarometer: Eine repr\u00e4sentative Bev\u00f6lkerungsumfrage zu Wissenschaft und Forschung<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=DLLvIQxQwLs\" target=\"_blank\" rel=\"noopener\">Diskussion der Ergebnisse des Wissenschaftsbarometers 2020 auf YouTube <\/a><\/li>\n<li><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/fileadmin\/user_upload\/Projekte\/Wissenschaftsbarometer\/Dokumente_20\/WiD-Wissenschaftsbarometer_2020_Broschuere_final.pdf\" target=\"_blank\" rel=\"noopener\">Booklet Wissenschaftsbarometer 2020<\/a> (PDF)<\/li>\n<li><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/fileadmin\/user_upload\/Projekte\/Wissenschaftsbarometer\/Dokumente_20\/20_WiD_Fragebogen_Wissenschaftsbarometer2020_final.pdf\" target=\"_blank\" rel=\"noopener\">Fragebogen Wissenschaftsbarometer 2020<\/a> (PDF)<\/li>\n<li><a href=\"https:\/\/www.wissenschaft-im-dialog.de\/fileadmin\/user_upload\/Projekte\/Wissenschaftsbarometer\/Dokumente_20\/20_WiD_Tabellenband_Wissenschaftsbarometer2020_final.pdf\" target=\"_blank\" rel=\"noopener\">Detaillierte Ergebnisse des Wissenschaftsbarometers nach Subgruppen<\/a> (PDF)<\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2020\/12\/barometer-fuer-die-wissenschaft-2019-20-neue-erkenntnisse-fuer-open-science\/\" target=\"_blank\" rel=\"noopener\">Barometer f\u00fcr die Wissenschaft 2019\/20: Neue Erkenntnisse f\u00fcr Open Science?<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2019\/02\/zukunftsreport-wer-kann-das-wissenschaftssystem-transformieren\/\" target=\"_blank\" rel=\"noopener\">Zukunftsreport: Wer kann das Wissenschaftssystem transformieren?<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2020\/06\/open-economics-studie-zu-open-science-prinzipien-und-praxis-in-den-wirtschaftswissenschaften\/\" target=\"_blank\" rel=\"noopener\">Open Economics: Studie zu Open-Science-Prinzipien und -Praxis in den Wirtschaftswissenschaften<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2020\/06\/open-economics-studie-zu-open-science-prinzipien-und-praxis-in-den-wirtschaftswissenschaften\/\" target=\"_blank\" rel=\"noopener\">Open Science im Maschinenraum der Forschung angekommen: ZBW-Panel auf der VfS-Jahrestagung 2019<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2019\/05\/guidelines-open-peer-review-verfahren-einfach-implementieren-und-akzeptanz-foerdern\/\" target=\"_blank\" rel=\"noopener\">Guidelines: Open-Peer-Review-Verfahren einfach implementieren und Akzeptanz f\u00f6rdern<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2017\/07\/social-media-und-wissenschaftskommunikation-statistenrolle-fuer-open-science-in-der-stellungnahme-2\/\" target=\"_blank\" rel=\"noopener\">Social Media und Wissenschaftskommunikation: Statistenrolle f\u00fcr Open Science in der Stellungnahme?<\/a><\/li>\n<\/ul>\n<div class='eckosc eckosc_contrast_block'><div class='eckosc_contrast_block_inner'>\n<p><b>\u00dcber die Autorin:<\/b><\/p>\n<p><b>Claudia Sittner<\/b> studierte Journalistik und Sprachen in Hamburg und London. Sie war lange Zeit Referentin beim von der ZBW herausgegebenen <a href=\"https:\/\/www.wirtschaftsdienst.eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Wirtschaftsdienst \u2013 Zeitschrift f\u00fcr Wirtschaftspolitik<\/a> und ist heute Redakteurin des Blogs ZBW MediaTalk. Au\u00dferdem ist sie freiberufliche <a href=\"https:\/\/weltreize.com\/\" target=\"_blank\" rel=\"noopener\">Reise-Bloggerin<\/a>. Sie ist auch auf <a href=\"https:\/\/de.linkedin.com\/in\/claudia-sittner-708951206\" target=\"_blank\" rel=\"noopener\">LinkedIn<\/a>, <a href=\"https:\/\/twitter.com\/ClaudiaSittner\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> und <a href=\"https:\/\/www.xing.com\/profile\/Claudia_Sittner\/\" target=\"_blank\" rel=\"noopener\">Xing<\/a> zu finden.<br \/>\nPortr\u00e4t: Claudia Sittner&copy;<\/p>\n<p>Die Verwendung der Grafiken der Ergebnisse ist unter Nennung der Quelle &#8220;Wissenschaft im Dialog\/Kantar Emnid&#8221; m\u00f6glich. Die Grafiken laufen unter der Lizenz <a href=\"https:\/\/www.creativecommons.org\/licenses\/by-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"noopener\">[CC BY-ND 4.0]<\/a>, Anpassungen des Formats f\u00fcr redaktionelle Ver\u00f6ffentlichungen sind erlaubt. <\/a><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Welches Bild hat die \u00d6ffentlichkeit in Deutschland von Wissenschaft und Forschung? Dieser Frage widmet sich das Wissenschaftsbarometer. Wir haben die Ergebnisse der neuesten Befragung unter Open-Science-Gesichtspunkten unter die Lupe genommen. <\/p>\n","protected":false},"author":19,"featured_media":38138,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_has_post_settings":[],"footnotes":""},"categories":[1147],"tags":[2471,2360,2356,2358,1687],"hashtags":[],"class_list":["post-38087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-open-science-de","tag-umfragen","tag-vertrauen-de","tag-wissenschaft-und-forschung","tag-wissenschaftsbarometer","tag-wissenschaftssysteme"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/38087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/comments?post=38087"}],"version-history":[{"count":5,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/38087\/revisions"}],"predecessor-version":[{"id":47525,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/38087\/revisions\/47525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media\/38138"}],"wp:attachment":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media?parent=38087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/categories?post=38087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/tags?post=38087"},{"taxonomy":"hashtags","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/hashtags?post=38087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}