{"id":34426,"date":"2017-04-11T09:38:54","date_gmt":"2017-04-11T09:38:54","guid":{"rendered":"https:\/\/www.zbw-mediatalk.eu?p=34426"},"modified":"2019-09-11T09:54:57","modified_gmt":"2019-09-11T09:54:57","slug":"monitor-digitale-bildung-hochschulen-digitalisierung-ja-open-education-nein-2","status":"publish","type":"post","link":"https:\/\/www.zbw-mediatalk.eu\/de\/2017\/04\/monitor-digitale-bildung-hochschulen-digitalisierung-ja-open-education-nein-2\/","title":{"rendered":"Monitor Digitale Bildung Hochschulen: Digitalisierung ja, Open Education nein"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:5381,&quot;href&quot;:&quot;https:\\\/\\\/www.bertelsmann-stiftung.de\\\/de\\\/themen\\\/aktuelle-meldungen\\\/2017\\\/maerz\\\/studierende-sind-keine-digitalen-enthusiasten&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:4531,&quot;href&quot;:&quot;https:\\\/\\\/www.bertelsmann-stiftung.de\\\/de\\\/unsere-projekte\\\/teilhabe-in-einer-digitalisierten-welt\\\/projektthemen\\\/projektthemen-monitor&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20251216161914\\\/https:\\\/\\\/www.bertelsmann-stiftung.de\\\/de\\\/unsere-projekte\\\/teilhabe-in-einer-digitalisierten-welt\\\/projektthemen\\\/projektthemen-monitor\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-14 13:39:26&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-03-27 21:06:11&quot;,&quot;http_code&quot;:403},{&quot;date&quot;:&quot;2026-05-05 16:27:24&quot;,&quot;http_code&quot;:403}],&quot;broken&quot;:true,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-05 16:27:24&quot;,&quot;http_code&quot;:403},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:4532,&quot;href&quot;:&quot;http:\\\/\\\/www.digitalisierung-bildung.de\\\/2017\\\/03\\\/22\\\/interview-mit-prof-dr-kerstin-mayrberger-studierende-muessen-mitgenommen-werden&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;http:\\\/\\\/blogs.bertelsmann-stiftung.de\\\/&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p>Der im M\u00e4rz 2017 von der Bertelsmann Stiftung und dem CHE \u2013 Centrum f\u00fcr Hochschulentwicklung ver\u00f6ffentlichte Monitor <a href=\"https:\/\/www.bertelsmann-stiftung.de\/de\/themen\/aktuelle-meldungen\/2017\/maerz\/studierende-sind-keine-digitalen-enthusiasten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Digitale Bildung \u2013 Die Hochschulen im digitalen Zeitalter<\/a> bildet den Stand der Digitalisierung der Hochschullehre in Deutschland ab. An der Online-Befragung teilgenommen haben 2.759 Studierende, 662 Lehrende und 84 Personen aus Hochschulleitungen und \u2013verwaltungen deutscher Hochschulen. Dar\u00fcber hinaus wurden 10 Fachleute aus \u00fcberregionalen Institutionen und Beh\u00f6rden leitfadengest\u00fctzt interviewt. <\/p>\n\n<h4>Gute Ausstattung, ungenutzte Potentiale<\/h4>\n<p>Die technische Ausstattung deutscher Hochschulen wird von den Befragten als \u00fcberwiegend gut bewertet. Die technische Ausstattung scheint daher nicht die Digitalisierung der Lehre zu limitieren. Das vorhandene Potential wird aber nicht ausgesch\u00f6pft. Hochschulen schaffen bislang der Befragung zufolge zwar geeignete materielle Voraussetzungen f\u00fcr die digitale Lehre, \u00fcberlassen es aber den einzelnen Hochschulangeh\u00f6rigen, diese in Eigenregie mit Leben zu f\u00fcllen. Wenig verwunderlich daher, dass die Digitalisierung der Lehre bislang nicht den Beitrag zur Bew\u00e4ltigung von Herausforderungen wie der wachsenden Studierendenzahl, der Internationalisierung der Hochschulen, personalisiertem Lernen und individuellem F\u00f6rdern oder der Inklusion nicht-traditioneller Studentenzielgruppen leisten kann, den sie bringen k\u00f6nnte, wenn sie nicht in erster Linie am Engagement einzelner Vorreiter h\u00e4ngen w\u00fcrde. <\/p>\n<p>Der Befragung zufolge k\u00f6nnen mit digitalen Medien, wie Lernvideos und Pr\u00e4sentationstools, oder durch Nutzung von Lernmanagement-Plattformen angereicherte teil-digitalisierte Lehrveranstaltungen als normal  betrachtet werden. Die Chancen weitergehender didaktischer Ver\u00e4nderungen wie des Inverted-Classroom-Konzepts bleiben ungenutzt. Dabei w\u00fcrde sich rund die H\u00e4lfte der Studierenden f\u00fcr Inverted-Classroom-Formate begeistern. Im Gegensatz dazu w\u00fcrden nur 14 Prozent der Lehrenden einen Einsatz von \u00fcberwiegend Videos zur Veranstaltungsvorbereitung begr\u00fc\u00dfen. Wenig verbreitet sind bislang auch andere innovative Lernformate, wie zum Beispiel soziales und kollaboratives Lernen (etwa mit Blogs, Wikis, Social Media), Simulationen und Planspiele oder auch elektronische Pr\u00fcfungen. Lange etablierte Anwendungen und Technologien pr\u00e4gen das Geschehen. Dazu z\u00e4hlen Pr\u00e4sentationstools wie PowerPoint und andere Office-Programme sowie digitale Dokumente und Texte.   <\/p>\n<h4>Von Open Education noch meilenweit entfernt<\/h4>\n<p>Open Educational Resources (OER) werden zwar prinzipiell von Lehrenden begr\u00fc\u00dft, da sie Lehrveranstaltungen bereichern und deren Vorbereitung vereinfachen k\u00f6nnten, allerdings nicht fl\u00e4chendeckend eingesetzt. Dies liegt unter anderem an vorhandener Unsicherheit bez\u00fcglich ihrer Qualit\u00e4t und urheberrechtlichen Aspekten, wenn diese geteilt werden. Als weiteren Hinderungsgrund nennen Lehrende, dass sie nicht gen\u00fcgend Zeit haben w\u00fcrden, um angesichts der Un\u00fcbersichtlichkeit passende Open Educational Resources zu finden. Fast 40 Prozent der befragten Lehrenden hatten sogar Zweifel an der Existenz geeigneter OER f\u00fcr ihr Fachgebiet. <\/p>\n<p>Wenn Lehrende entsprechende Materialien teilen, so geschieht dies bevorzugt nicht \u201eopen\u201c, sondern etwa per E-Mail, ausgedruckt oder auf einem USB-Stick an Kolleginnen und Kollegen, oder innerhalb eines Lernmanagementsystems an Studierende. Zudem schwingt bei OER die Sorge mit, dass eigene Materialien weiterverarbeitet und ver\u00e4ndert werden k\u00f6nnten. Es wurden in der Befragung nur zwei F\u00e4lle genannt, in denen <a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2017\/02\/wissenschaft-auf-youtube-ein-beitrag-zur-offenheit\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hochschullehrende Inhalte auf YouTube<\/a> einstellen. Open Education erscheint in Anbetracht dessen an deutschen Hochschulen eher noch als Fernziel. Damit kann sie auch noch nicht den von ihr erhofften Beitrag zur \u00d6ffnung von Hochschulen f\u00fcr neue Zielgruppen und Erh\u00f6hung der sozialen Teilhabe leisten.   <\/p>\n<h4>MOOCs in der Lehre nicht etabliert<\/h4>\n<p>Zu den am st\u00e4rksten diskutierten Formaten z\u00e4hlen <a href=\"ttps:\/\/www.zbw-mediatalk.eu\/2014\/11\/moocs-one-size-fits-all\/\" target=\"_blank\" rel=\"noopener noreferrer\">MOOCS<\/a>. F\u00fcr ihre eigene Fortbildung oder zur Vorbereitung nutzen Lehrende sie zwar, setzen sie in der Lehre jedoch kaum ein. Allenfalls im Rahmen <a href=\" https:\/\/www.zbw-mediatalk.eu\/2016\/07\/digitale-weiterbildung-ein-leben-lang-lernen\/\" target=\"_blank\" rel=\"noopener noreferrer\">akademischer Weiterbildungsangebote<\/a> spielen MOOCs eine etwas gr\u00f6\u00dfere Rolle. <\/p>\n<h4>Studierende sind keine digitalen Enthusiasten<\/h4>\n<p>Auch wenn viele Studierende digitale und soziale Medien privat auch f\u00fcr das Lernen nutzen und sich an der Hochschule einen Methoden-Mix w\u00fcnschen, so kann von ihnen nicht erwartet werden, dass sie zum Treiber der Digitalisierung an der Hochschule werden, wie dies von Seiten der Hochschulleitungen und \u2013verwaltungen oft erhofft wird. Sie nutzen die von den Lehrenden zur Verf\u00fcgung gestellten digitalen M\u00f6glichkeiten, treiben die Entwicklung aber nicht von sich aus weiter voran, auch wenn sie digitalen Medien und ihrem innovativen Einsatz in der Lehre aufgeschlossen gegen\u00fcberstehen. Zudem zeigt die Studie auch, dass Studierende nicht generell digitale Medien und Formate pr\u00e4ferieren, sondern ihnen der fachliche Fokus der Lehrenden deutlich wichtiger ist, und sie auch herk\u00f6mmliche Tafel-und-Kreide-Vortr\u00e4ge zu sch\u00e4tzen wissen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung.jpg\" alt=\"\" width=\"1381\" height=\"710\" class=\"alignleft size-full wp-image-28690\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung.jpg 1381w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-300x154.jpg 300w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-768x395.jpg 768w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-1024x526.jpg 1024w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-1240x638.jpg 1240w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-860x442.jpg 860w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-680x350.jpg 680w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-500x257.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-400x206.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-200x103.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-50x26.jpg 50w\" sizes=\"auto, (max-width: 1381px) 100vw, 1381px\" \/><\/p>\n<p>F\u00fcr das private Lernen nutzen 41 Prozent der Studierenden Foren und Blogs, 29 Prozent soziale Netzwerke und 42 Prozent Chat-Dienste. In der Hochschullehre sind diese allerdings bislang kaum f\u00fcr den Austausch unter Studierenden oder auch mit Lehrenden institutionalisiert. Am ehesten werden hierf\u00fcr noch Chat-Dienste eingesetzt (17 Prozent). Beim privaten Lernen noch verbreiteter ist der \u201eKlassiker\u201c Wikis beziehungsweise Wikipedia, der von mehr als zwei Drittel der Studierenden (70 Prozent) informell genutzt wird.  Auch Lehrende nutzen diese intensiv zur Vorbereitung ihrer Veranstaltungen (64 Prozent), ohne sie jedoch in den Lehrveranstaltungen selbst viel einzusetzen.<\/p>\n<h4>Lehramtsstudierende wecken Zweifel an Digitalisierung der Schulen <\/h4>\n<p>Aus allen Studentengruppen stechen Lehramtsstudierende hervor: Im Vergleich zu anderen F\u00e4chergruppen setzen sie digitale Lernmedien weniger in Lehrveranstaltungen oder eigenst\u00e4ndig f\u00fcr das Studium ein und sind von deren Einsatz zudem besonders wenig motiviert. Im Hinblick darauf, dass hier die zuk\u00fcnftigen Lehrerinnen und Lehrer ausgebildet werden, stimmt dies f\u00fcr den Einsatz digitaler Medien an Schulen und f\u00fcr die Vorbereitung von Sch\u00fclerinnen und Sch\u00fclern auf eine digitalisierte Arbeitswelt nachdenklich.<\/p>\n<h4>Engagierte Lehrende digitalisieren Lehre in Eigenregie<\/h4>\n<p>Bislang wird die Digitalisierung der Lehre vor allem von Lehrenden mit digitaler Affinit\u00e4t vorangetrieben. Anreize und interne Unterst\u00fctzungsservices erscheinen bislang nicht ausreichend zu sein. Gleiches gilt f\u00fcr die Qualifizierung und didaktische Beratung der Lehrenden. Knapp 40 Prozent der Lehrenden sehen in der fehlenden didaktischen Betreuung einen gro\u00dfen Mangel, obwohl 84 Prozent der Hochschulleitungen und Verwaltungsmitarbeiter angeben, dass es an ihren Hochschulen Beratungs- und Unterst\u00fctzungsangebote g\u00e4be. So sind es bislang \u00fcberwiegend die Lehrenden selbst, die sich in Eigeninitiative f\u00fcr die digitale Lehre qualifizieren. Als prinzipiell auch geeignete Fortbildungsma\u00dfnahmen wurden unter anderem genannt:  Tutor-Programme, mehrw\u00f6chige Schulungen, Webinare mit Gamification-Charakter und verpflichtende Einstiegsprogramme.<\/p>\n<h4>Hochschulleitungen m\u00fcssen als Change Agents handeln <\/h4>\n<p>Knapp die H\u00e4lfte der Befragten aus Hochschulleitung und Verwaltung sieht noch \u201eLuft nach oben\u201c in Bezug auf den strategischen Handlungsbedarf bei der hochschulweiten \u201eAnwendung\u201c des digitalen Lernens. An 55 Prozent der untersuchten Hochschulen werden digitale Lernmedien \u201ehochschulweit systematisch\u201c eingesetzt. Dass daf\u00fcr bereits die Nutzung einer hochschulweit eingef\u00fchrten Lernmanagementplattform zum Up- und Download als \u201ehochschulweiter Einsatz\u201c z\u00e4hlt, relativiert dieses Ergebnis allerdings.<\/p>\n<p>\u201eJede Hochschule hat eines oder mehrere LMS: Die Frage ist, ob die Systeme genutzt werden und wenn ja, wof\u00fcr. Stichwort: \u201epdf-Schleuder\u201c. <\/p>\n<blockquote><p>Die Verbindung der einzelnen Elemente ist eine Herausforderung. Eine weitere Herausforderung sind Infrastrukturen, die au\u00dferhalb der Hochschule liegen, wie bestimmte Videoplattformen o. \u00c4.\u201c (Befragungsteilnehmer, m\u00e4nnlich, 40 Jahre) <\/p><\/blockquote>\n<p>Als Agenten des Wandels sind nach Ansicht von Hochschulexperten vor allem die Hochschulleitungen gefordert, die den Rahmen f\u00fcr eine umsetzbare Digitalisierungsstrategie schaffen sollten. Allerdings kommt der Digitalisierung der Lehre an den meisten Hochschulen lediglich eine mittlere strategische Bedeutung zu. Die Personen in Hochschulleitungen und -verwaltungen scheinen zudem in zwei Lager geteilt zu sein: Digitale Verfechter und analoge Skeptiker. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik.jpg\" alt=\"\" width=\"648\" height=\"710\" class=\"aligncenter size-full wp-image-28691\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik.jpg 648w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik-274x300.jpg 274w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik-500x548.jpg 500w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik-400x438.jpg 400w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik-200x219.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2017\/04\/MT-MonitorDigitaleBildung-Grafik-50x55.jpg 50w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/p>\n<p>Als konkrete Probleme werden von ihnen neben datenschutz- und nutzungsrechtlichen Fragestellungen auch fehlende oder nicht ausreichende Regelungen hinsichtlich der Anrechnung des Aufwands digitaler Lehre auf das Lehrdeputat genannt. M\u00f6glicherweise herrschte bei vielen Befragten allerdings Unkenntnis \u00fcber die in vielen Bundesl\u00e4ndern bereits vorhandenen Anrechnungsm\u00f6glichkeiten. Als weiterer Hinderungsgrund f\u00fcr digitale Lehre wurden hohe Beschaffungskosten, etwa f\u00fcr die Lizenzierung elektronischer Fachzeitschriften, genannt sowie die nicht ausreichende Betreuung der digitalen Infrastruktur. <\/p>\n<h4>Weiterf\u00fchrende Quellen:<\/h4>\n<ul>\n<li><a href=\"https:\/\/www.bertelsmann-stiftung.de\/de\/unsere-projekte\/teilhabe-in-einer-digitalisierten-welt\/projektthemen\/projektthemen-monitor\/\" target=\"_blank\" rel=\"noopener noreferrer\">Monitor Digitale Bildung<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/de\/2016\/04\/digital-natives-bleiben-draussen-wie-lernen-studierende-mit-digitalen-medien\/\" target=\"_blank\" rel=\"noopener noreferrer\">Digital Natives bleiben drau\u00dfen: Wie lernen Studierende mit Digitalen Medien?<\/a><\/li>\n<li><a href=\"https:\/\/www.zbw-mediatalk.eu\/2015\/10\/moderator-zwischen-makerspace-und-mooc-im-rahmen-des-studiums-wandelt-sich-die-rolle-von-bibliotheken\/2 Target=\"_blank\" rel=\"noopener noreferrer\">Moderator zwischen Makerspace und MOOC? Im Rahmen des Studiums wandelt sich die Rolle von Bibliotheken<\/a><\/li>\n<li><a href=\"2020 https:\/\/www.zbw-mediatalk.eu\/2016\/06\/8-thesen-fuer-die-arbeitswelt-4-0-hochschul-bildungs-report-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">8 Thesen f\u00fcr die Arbeitswelt 4.0 \u2013 Hochschul-Bildungsreport 2020<\/a><\/li>\n<li> Interview mit Prof. Dr. Kerstin Mayrberger: <a href=\"http:\/\/www.digitalisierung-bildung.de\/2017\/03\/22\/interview-mit-prof-dr-kerstin-mayrberger-studierende-muessen-mitgenommen-werden\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u201eStudierende m\u00fcssen mitgenommen werden\u201c<\/a><\/li>\n<\/ul>\n\n","protected":false},"excerpt":{"rendered":"<p>Der k\u00fcrzlich ver\u00f6ffentlichte Monitor Digitale Bildung beleuchtet den Stand der Digitalisierung der Lehre an deutschen Hochschulen. Demnach erscheinen teil-digitalisierte Lehrveranstaltungen mittlerweile als Standard, Studierende erweisen sich nicht wie von manchen erhofft als die treibende Kraft der digitalen Transformation und das volle Potential der Digitalisierung wird bislang nicht ann\u00e4hernd ausgesch\u00f6pft. Open Education muss folglich eher als Fernziel betrachtet werden. <\/p>\n","protected":false},"author":6,"featured_media":34614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_has_post_settings":[],"footnotes":""},"categories":[1147],"tags":[1309,1943,1495,1560,1559],"hashtags":[],"class_list":["post-34426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-open-science-de","tag-digitalisierung","tag-hochschullehre","tag-moocs-de","tag-open-educational-resources-de","tag-open-educations-de"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/34426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/comments?post=34426"}],"version-history":[{"count":0,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/34426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media\/34614"}],"wp:attachment":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media?parent=34426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/categories?post=34426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/tags?post=34426"},{"taxonomy":"hashtags","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/hashtags?post=34426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}