{"id":34345,"date":"2019-03-06T12:55:42","date_gmt":"2019-03-06T12:55:42","guid":{"rendered":"https:\/\/www.zbw-mediatalk.eu?p=34345"},"modified":"2021-09-09T13:25:06","modified_gmt":"2021-09-09T13:25:06","slug":"praxisbericht-open-science-diese-tools-foerdern-die-zusammenarbeit","status":"publish","type":"post","link":"https:\/\/www.zbw-mediatalk.eu\/de\/2019\/03\/praxisbericht-open-science-diese-tools-foerdern-die-zusammenarbeit\/","title":{"rendered":"Praxisbericht Open Science: Diese Tools f\u00f6rdern die Zusammenarbeit"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:3202,&quot;href&quot;:&quot;https:\\\/\\\/www.zbw.eu\\\/de\\\/forschung\\\/science-2-0\\\/q-aktiv&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20221003005335\\\/https:\\\/\\\/www.zbw.eu\\\/de\\\/forschung\\\/science-2-0\\\/q-aktiv&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-14 05:57:24&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-03 13:02:27&quot;,&quot;http_code&quot;:503},{&quot;date&quot;:&quot;2026-04-10 13:16:12&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-29 09:19:24&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:24&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3203,&quot;href&quot;:&quot;https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/GitLab&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260314062610\\\/https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/GitLab&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-10 13:16:07&quot;,&quot;http_code&quot;:429},{&quot;date&quot;:&quot;2026-04-29 09:19:27&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:27&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3204,&quot;href&quot;:&quot;https:\\\/\\\/www.jitsi.org\\\/jitsi-meet&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260314062635\\\/https:\\\/\\\/jitsi.org\\\/jitsi-meet\\\/&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/jitsi.org\\\/jitsi-meet\\\/&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-10 13:16:08&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-29 09:19:28&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:28&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3205,&quot;href&quot;:&quot;https:\\\/\\\/de.overleaf.com&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260219235839\\\/https:\\\/\\\/de.overleaf.com\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-14 05:57:43&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-29 09:19:38&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:38&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3206,&quot;href&quot;:&quot;https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/LaTeX&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260301054223\\\/https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/LaTeX&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-14 05:57:46&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-29 09:19:36&quot;,&quot;http_code&quot;:429}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:36&quot;,&quot;http_code&quot;:429},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3207,&quot;href&quot;:&quot;https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Git&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260311125728\\\/https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Git&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-14 05:57:48&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-04-29 09:19:37&quot;,&quot;http_code&quot;:429}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:37&quot;,&quot;http_code&quot;:429},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3208,&quot;href&quot;:&quot;https:\\\/\\\/about.gitlab.com&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3209,&quot;href&quot;:&quot;https:\\\/\\\/de.atlassian.com\\\/software\\\/jira&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.atlassian.com\\\/de\\\/software\\\/jira&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3210,&quot;href&quot;:&quot;https:\\\/\\\/de.atlassian.com\\\/software\\\/trello&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20190715071601\\\/https:\\\/\\\/de.atlassian.com\\\/software\\\/trello&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/www.atlassian.com\\\/de\\\/software\\\/trello&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-29 09:19:41&quot;,&quot;http_code&quot;:206}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:19:41&quot;,&quot;http_code&quot;:206},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5228,&quot;href&quot;:&quot;https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Alan_Turing&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260326131446\\\/https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Alan_Turing&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-29 09:20:03&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-04-29 09:20:03&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5229,&quot;href&quot;:&quot;https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Markdown&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3214,&quot;href&quot;:&quot;https:\\\/\\\/www.gnu.org\\\/philosophy\\\/free-sw.html&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:3215,&quot;href&quot;:&quot;https:\\\/\\\/www.gnu.org\\\/philosophy\\\/open-source-misses-the-point.html&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260301052920\\\/https:\\\/\\\/www.gnu.org\\\/philosophy\\\/open-source-misses-the-point.html&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-14 05:58:37&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-04-02 00:15:41&quot;,&quot;http_code&quot;:206},{&quot;date&quot;:&quot;2026-05-12 19:10:00&quot;,&quot;http_code&quot;:503}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-12 19:10:00&quot;,&quot;http_code&quot;:503},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:5230,&quot;href&quot;:&quot;https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Richard_Stallman&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20251222012630\\\/https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Richard_Stallman&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-03-26 13:13:48&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-03-26 13:13:48&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p><b>im Interview mit Lukas Galke<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412.jpg\" alt=\"\" width=\"275\" height=\"412\" class=\"alignleft size-full wp-image-33173\" srcset=\"https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412.jpg 275w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412-200x300.jpg 200w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412-250x375.jpg 250w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412-100x150.jpg 100w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412-76x114.jpg 76w, https:\/\/www.zbw-mediatalk.eu\/wp-content\/uploads\/2019\/03\/LukasGalke-Portraeit-275x412-50x75.jpg 50w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/>Tools f\u00fcr die digitale Kollaboration sind ein zentraler Baustein von Open Science. Doch die Vielfalt an verf\u00fcgbaren Tools ist kaum zu \u00fcberblicken; das Zusammenstellen eines geeigneten Portfolios ist komplex. In unserem Interview gibt Lukas Galke einen Einblick in seine Projektpraxis und erl\u00e4utert Kriterien f\u00fcr die Auswahl geeigneter Tools. Er ist wissenschaftlicher Mitarbeiter im Projekt <a href=\"https:\/\/www.zbw.eu\/de\/forschung\/science-2-0\/q-aktiv\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u201eQ-Aktiv\u201c<\/a> an der ZBW. In dem Projekt werden Dynamiken des Wissenschafts- und Innovationssystems analysiert und Forschungsfragen bearbeitet wie: Wie verschmelzen bestehende Wissenschafts- und Technologiebereiche? Oder: Welche Fusion von Wissensgebieten und Technologien kann vorhergesagt werden? Verbundpartner der ZBW sind der Lehrstuhl f\u00fcr Technologiemanagement an der Universit\u00e4t Kiel und die ZB MED \u2013 Informationszentrum Lebenswissenschaften.<\/p>\n<h4><span style=\"color: #0a387a;\">Wie organisierst du deinen Projektalltag in Q-Aktiv?<\/span><\/h4>\n<p>Wir sind im Projekt drei wissenschaftliche Mitarbeiterinnen und Mitarbeiter, die r\u00e4umlich an verschiedenen Pl\u00e4tzen arbeiten. Sich hier auszutauschen und Zwischenergebnisse zu diskutieren, gemeinsam zu arbeiten und sich zu koordinieren, ist essenziell. Wir setzen hier sehr intensiv auf kollaborative Werkzeuge.  Grob kann man diese Werkzeuge hinsichtlich ihres Zwecks unterteilen: Kommunikation, Kooperation und Koordination.<\/p>\n<h4><span style=\"color: #0a387a;\">K\u00f6nntest du uns im Detail erl\u00e4utern, welche Tools ihr einsetzt?<\/span><\/h4>\n<p>Zur Gruppe \u201eKommunikation\u201c geh\u00f6ren zum einen die asynchronen Werkzeuge, mit denen ich zeitversetzt Nachrichten \u00fcbermitteln kann. In Q-Aktiv benutzen wir nat\u00fcrlich E-Mails, aber  auch Issues in <a href=\"https:\/\/de.wikipedia.org\/wiki\/GitLab\" target=\"_blank\" rel=\"noopener noreferrer\">GitLab<\/a>. Zum anderen geh\u00f6ren in diese Gruppe die synchronen Werkzeuge f\u00fcr Audio- und Videokonferenzen. Hierf\u00fcr verwenden wir vorzugsweise <a href=\"https:\/\/www.jitsi.org\/jitsi-meet\/\" target=\"_blank\" rel=\"noopener noreferrer\">Jitsi-Meet<\/a> statt beispielsweise Skype.<\/p>\n<p>Zur Gruppe \u201eKooperation\u201c geh\u00f6ren solche Tools, die verteilte Zusammenarbeit erm\u00f6glichen. Die wesentlichen Eigenschaften  dieser Tools sind Zugriffs- und Versionskontrolle. W\u00e4hrend die Zugriffskontrolle eben jenen verteilten Zugriff f\u00fcr die teilnehmenden Akteure erlauben sollte, ist die Versionskontrolle hierbei wichtig, um unterschiedliche Versionen der jeweiligen Akteure bestm\u00f6glich zusammenzuf\u00fchren und gegebenenfalls auch \u00c4nderungen r\u00fcckg\u00e4ngig machen zu k\u00f6nnen.<\/p>\n<p>In Q-Aktiv verwenden wir je nach Anwendungsfall verschiedene kollaborative Werkzeuge zur Kooperation. F\u00fcr wissenschaftliche Artikel verwenden wir <a href=\"https:\/\/de.overleaf.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Overleaf<\/a>. Overleaf ist ein <a href=\"https:\/\/de.wikipedia.org\/wiki\/LaTeX\" target=\"_blank\" rel=\"noopener noreferrer\">Latex-Editor<\/a> im Browser, der auch synchrone Bearbeitung unterst\u00fctzt. Die Versionskontrolle wird durch Git umgesetzt, sodass es auch m\u00f6glich ist, den Latex-Code lokal zu bearbeiten und die \u00c4nderungen zeitversetzt einzuspielen. Um Overleaf zu nutzen, ist keine lokale Latex-Installation notwendig. Zusammen mit automatischem Kompilieren und Hinweisen auf Fehler im Latex-Code, erleichtert dies das Arbeiten mit und den Einstieg in Latex ungemein.<\/p>\n<p>Wenn es hingegen darum geht, gemeinsam am Quellcode f\u00fcr Programme oder Experimente zu arbeiten, verlassen wir uns auf <a href=\"https:\/\/de.wikipedia.org\/wiki\/Git\" target=\"_blank\" rel=\"noopener noreferrer\">Git<\/a>. Als Plattform f\u00fcr Git verwenden wir <a href=\"https:\/\/about.gitlab.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">GitLab<\/a>. GitLab verh\u00e4lt sich zu Git wie Overleaf zu Latex. Es stellt ein zentrales Hosting  zur Verf\u00fcgung und bietet diverse Convenience-Features, um sich beispielsweise die \u00c4nderungen zwischen zwei Versionen anzuschauen und diese zu kommentieren. <\/p>\n<p>Im Bereich der \u201eKoordination\u201c sind insbesondere das Definieren von Action-Items und Meilensteinen relevant. Auch hierf\u00fcr gibt es kollaborative Werkzeuge wie zum Beispiel Atlassians <a href=\"https:\/\/de.atlassian.com\/software\/jira\" target=\"_blank\" rel=\"noopener noreferrer\">Jira<\/a> oder <a href=\"https:\/\/de.atlassian.com\/software\/trello\" target=\"_blank\" rel=\"noopener noreferrer\">Trello<\/a>. In Q-Aktiv verwenden wir jedoch auch f\u00fcr die Koordination GitLab. In GitLab k\u00f6nnen Issues angelegt, gegebenenfalls einzelnen Akteuren zugewiesen sowie Meilensteinen zugeordnet werden. Insbesondere k\u00f6nnen auch weitere Details innerhalb des Issues diskutiert werden. Zudem verwenden wir Git oder GitLab auch, um gemeinsam an Agenden f\u00fcr Projekttreffen oder Workshops zu arbeiten, deren Protokolle festzuhalten, relevante Literatur auszutauschen, ein gemeinsames Vokabular festzuhalten und Pr\u00e4sentationsfolien zu teilen. Hierf\u00fcr haben wir innerhalb der Projektgruppe ein spezielles, separates Repositorium angelegt.<\/p>\n<h4><span style=\"color: #0a387a;\">Warum spielt GitLab eine zentrale Rolle bei der Kollaboration in eurem Projekt?<\/span><\/h4>\n<p>Der gro\u00dfe Vorteil von Plattformen wie GitLab ist, dass sie gleichzeitig viele verschiedene Anforderungen abdecken. Dies empfinde ich als sehr angenehm, da es einen zentralen Einstiegspunkt darstellt, sodass ich nicht manuell die Verbindung zwischen E-Mails, Quellcode, To-do-Items und Meilensteinen herstellen muss. Stattdessen ist dies \u00fcbersichtlich auf einer einzigen Plattform zusammengefasst und es k\u00f6nnen nach Belieben Querverweise erzeugt werden.<\/p>\n<p>Ein weiterer Vorteil von GitLab ist, dass es in der Community-Edition unter der MIT Lizenz steht. Dies bedeutet nicht nur, dass der Quellcode von GitLab transparent einsehbar ist, sondern auch, dass eine Institution oder auch eine Privatperson ihre eigene GitLab-Instanz aufsetzen kann und somit auf keinen externen Hosting-Provider angewiesen ist. Dies ist ein Alleinstellungsmerkmal gegen\u00fcber der j\u00fcngst von Microsoft akquirierten Konkurrenzplattform GitHub. Obwohl dies ein zentraler Platz \u2013 vermutlich aktuell der gr\u00f6\u00dfte \u2013 f\u00fcr Open-Source-Software ist, ist der Quellcode von GitHub selbst nicht offen.<\/p>\n<p>Bei den anderen Werkzeugen, die wir im Projekt verwenden, hatten wir bei der Auswahl \u00e4hnliche Beweggr\u00fcnde: Overleaf basiert auf freier Software (Git, Latex, ShareLatex). Wenn die zentrale Overleaf-Instanz ausf\u00e4llt, kann man nahtlos auf Git und Latex umsteigen. Nat\u00fcrlich braucht man dann gegebenenfalls die lokale Tex-Installation, falls nicht vorhanden. Bez\u00fcglich virtueller Projekttreffen oder Treffen im Arbeitskreis haben wir uns f\u00fcr Jitsi Meet entschieden. Jitsi Meet steht auch unter einer Open-Source-Lizenz (Apache 2.0) und bietet gleichzeitig eine komfortable Oberfl\u00e4che (ohne Login), um Videokonferenzen abzuhalten.<\/p>\n<h4><span style=\"color: #0a387a;\">An welchen Punkten sto\u00dfen eure aktuellen Werkzeuge an ihre Grenzen?<\/span><\/h4>\n<p>Haupts\u00e4chlich bei Word- und Powerpoint-Dateien. Diese lassen sich zwar wunderbar \u00fcber Git austauschen, jedoch ist hier die Versionskontrolle problematisch. Git vergleicht Dateien \u00fcblicherweise Zeile f\u00fcr Zeile. Word und Powerpoint-Dateien sind allerdings im gespeicherten Zustand nicht so strukturiert, dass sie sich Zeile f\u00fcr Zeile vergleichen lassen. Auch LibreOffice-Dokumente w\u00fcrden unter dem Aspekt nicht besser abschneiden. Git selbst st\u00f6\u00dft hier an seine Grenzen. W\u00e4hrend bestimmte Muster f\u00fcr Zwischenberichte oder Pr\u00e4sentationsfolien oft nur als Word\/Powerpoint- Templates vorhanden sind, schreiben wir wissenschaftliche Artikel vorzugsweise mit Latex. Latex ist eine <a href=\"https:\/\/de.wikipedia.org\/wiki\/Alan_Turing\" target=\"_blank\" rel=\"noopener noreferrer\">Turing<\/a>-vollst\u00e4ndige Programmiersprache und der Quellcode l\u00e4sst sich einwandfrei Zeile f\u00fcr Zeile vergleichen. Auf der anderen Seite verwenden wir <a href=\"https:\/\/de.wikipedia.org\/wiki\/Markdown\" target=\"_blank\" rel=\"noopener noreferrer\">Markdown<\/a> als flexibles Format f\u00fcr kleinere Dokumente.<\/p>\n<h4><span style=\"color: #0a387a;\">Was m\u00fcssen Tools k\u00f6nnen, um Kollaboration gut zu unterst\u00fctzen?<\/span><\/h4>\n<p>Wie bei allen Werkzeugen ist es wichtig, dass der Aufwand das Werkzeug zu verwenden (\u201eKosten\u201c) nicht gr\u00f6\u00dfer ist als der Nutzen, den das Werkzeug erbringt. Bei Kollaborationswerkzeugen ist der Nutzen im Allgemeinen die Zusammenarbeit, zum Beispiel zwischen Projektpartnern. Diese Kollaboration manifestiert sich jedoch in verschiedenen Aspekten  wie  Kommunikation, Kooperation und Koordination. F\u00fcr jeden dieser Aspekte muss gesondert abgewogen werden, ob sich die Verwendung eines Werkzeugs in Kosten\/Nutzen-Relation lohnt.<\/p>\n<p>Gute Kollaborationswerkzeuge sind also solche, bei denen die Kosten m\u00f6glichst gering  sind. Dadurch, dass der Nutzen des kollaborativen Arbeitens \u00fcblicherweise hoch ist, sind die Kosten oder der Aufwand oft der kritische Punkt. Wenn die Werkzeuge f\u00fcr mehrere Aspekte in einer Plattform zusammengefasst sind, sinken die \u201eKosten\u201c, die ben\u00f6tigt werden, um sich mit den jeweiligen Werkzeugen vertraut zu machen und dies zu benutzen. Es entstehen also Synergien zwischen den Werkzeugen. Abgesehen davon sollten gute Kollaborationswerkzeuge auf <i>freier<\/i> Software basieren. Ansonsten steigen nicht nur die indirekten Kosten bez\u00fcglich der Einarbeitung und dem Overhead f\u00fcr die Verwendung eines Werkzeugs, sondern auch direkte Kosten, beispielsweise durch zus\u00e4tzliche Lizenzgeb\u00fchren bei propriet\u00e4rer Software oder gegebenenfalls durch die Anpassung der Partnersysteme. Freie Software bedient sich \u00fcblicherweise etablierter und vor allem nicht propriet\u00e4rer Standards, wodurch stetig Synergieeffekte gef\u00f6rdert werden. Auch ein Linux-System basiert auf tausenden einzelnen Programmen, die so gut harmonieren, dass ein vollfunktionsf\u00e4higes Betriebssystem entsteht, obwohl jedes dieser Programme nur einem klar definierten Zweck dient und jeweils von einem anderen Programmierer entwickelt wurde.<\/p>\n<p>Zur\u00fcck zu Kollaborationswerkzeugen: Aus den Zutaten von vielen kleinen Werkzeugen entsteht also durch Synergien eine Art Men\u00fc f\u00fcr das kollaborative Arbeiten. Verpackt wird dieses Men\u00fc in Convenience-Tools wie GitLab und Overleaf. Es gibt nat\u00fcrlich auch andere Convenience-Tools, jedoch gilt hier der gleiche Grundsatz wie beim Essen. Convenience ist nur so gut wie die enthaltenen Zutaten. Beim Essen sind gute Zutaten wom\u00f6glich pflanzenbasiert und nat\u00fcrlich; bei Software sind gute Zutaten entsprechend <i>freie<\/i> und <i>offene<\/i> Software sowie etablierte Standards.<\/p>\n<h4><span style=\"color: #0a387a;\">Was ist dir pers\u00f6nlich bei der Nutzung kollaborativer Werkzeuge wichtig?<\/span><\/h4>\n<p>Bei kollaborativen Werkzeugen ist mir wie auch bei allen anderen Programmen wichtig, dass sie <i>frei<\/i> sind. <a href=\"https:\/\/www.gnu.org\/philosophy\/free-sw.html\" target=\"_blank\" rel=\"noopener noreferrer\"><i>Freie Software<\/i><\/a> bedeutet nicht nur, dass diese kostenlos verwendbar ist oder der Quellcode offenliegt, sondern <a href=\"https:\/\/www.gnu.org\/philosophy\/open-source-misses-the-point.html\" target=\"_blank\" rel=\"noopener noreferrer\">insbesondere<\/a>, dass &#8220;die Benutzerinnen und Benutzer die Freiheit haben, das Programm auszuf\u00fchren, zu kopieren, zu verteilen, zu studieren, zu ver\u00e4ndern und zu verbessern [, also] frei wie in freie Rede, nicht wie in Freibier.&#8221; &#8211; <a href=\"https:\/\/de.wikipedia.org\/wiki\/Richard_Stallman\" target=\"_blank\" rel=\"noopener noreferrer\">Richard Stallman<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welche Open-Science-Tools f\u00f6rdern die Zusammenarbeit in Forschungsprojekten? Lukas Galke berichtet im Interview von seinen Erfahrungen und gibt einen Einblick in das Toolportfolio, das er im Projekt \u201eQ-Aktiv\u201c f\u00fcr die digitale Kollaboration einsetzt.  <\/p>\n","protected":false},"author":4,"featured_media":34704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_has_post_settings":[],"footnotes":""},"categories":[1147],"tags":[1267,1765,1188,1678],"hashtags":[],"class_list":["post-34345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-open-science-de","tag-kollaboration-de","tag-werkzeuge-de","tag-wissenschaftskommunikation-de","tag-wissenschaftskommunikationen-de"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/34345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/comments?post=34345"}],"version-history":[{"count":2,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/34345\/revisions"}],"predecessor-version":[{"id":40454,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/34345\/revisions\/40454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media\/34704"}],"wp:attachment":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media?parent=34345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/categories?post=34345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/tags?post=34345"},{"taxonomy":"hashtags","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/hashtags?post=34345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}