{"id":1914,"date":"2011-10-19T09:28:10","date_gmt":"2011-10-19T09:28:10","guid":{"rendered":"https:\/\/www.zbw-mediatalk.eu\/?p=1914"},"modified":"2011-10-19T09:28:10","modified_gmt":"2011-10-19T09:28:10","slug":"web-gl-bookcase-google-zeigt-unendliche-buchregal","status":"publish","type":"post","link":"https:\/\/www.zbw-mediatalk.eu\/de\/2011\/10\/web-gl-bookcase-google-zeigt-unendliche-buchregal\/","title":{"rendered":"WebGL Bookcase: Google zeigt das unendliche Buchregal"},"content":{"rendered":"<div class='__iawmlf-post-loop-links' style='display:none;' data-iawmlf-post-links='[{&quot;id&quot;:6925,&quot;href&quot;:&quot;http:\\\/\\\/googleblog.blogspot.com\\\/2011\\\/10\\\/designing-infinite-digital-bookcase.html&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20260405183237\\\/https:\\\/\\\/googleblog.blogspot.com\\\/2011\\\/10\\\/designing-infinite-digital-bookcase.html&quot;,&quot;redirect_href&quot;:&quot;https:\\\/\\\/googleblog.blogspot.com\\\/2011\\\/10\\\/designing-infinite-digital-bookcase.html&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-07 12:06:08&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-01 01:18:22&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-11 00:42:05&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-11 00:42:05&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:6926,&quot;href&quot;:&quot;http:\\\/\\\/code.google.com\\\/apis\\\/books&quot;,&quot;archived_href&quot;:&quot;&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[],&quot;broken&quot;:false,&quot;last_checked&quot;:null,&quot;process&quot;:&quot;done&quot;},{&quot;id&quot;:6927,&quot;href&quot;:&quot;http:\\\/\\\/www.chromeexperiments.com\\\/detail\\\/webgl-bookcase&quot;,&quot;archived_href&quot;:&quot;https:\\\/\\\/web-wp.archive.org\\\/web\\\/20150209023554\\\/http:\\\/\\\/www.chromeexperiments.com:80\\\/detail\\\/webgl-bookcase\\\/&quot;,&quot;redirect_href&quot;:&quot;&quot;,&quot;checks&quot;:[{&quot;date&quot;:&quot;2026-04-05 18:29:36&quot;,&quot;http_code&quot;:200},{&quot;date&quot;:&quot;2026-05-04 22:38:01&quot;,&quot;http_code&quot;:200}],&quot;broken&quot;:false,&quot;last_checked&quot;:{&quot;date&quot;:&quot;2026-05-04 22:38:01&quot;,&quot;http_code&quot;:200},&quot;process&quot;:&quot;done&quot;}]'><\/div>\n<p>Ah, sweet innovation! Google l\u00e4sst mal wieder beil\u00e4ufig die Muskeln spielen und pr\u00e4sentierte am Dienstagabend das <a href=\"http:\/\/googleblog.blogspot.com\/2011\/10\/designing-infinite-digital-bookcase.html\" target=\"_blank\">WebGL Bookcase<\/a> &#8211; ein neuer Versuch, die Darstellung von B\u00fcchern im Web zeitgem\u00e4\u00dfer zu gestalten.<\/p>\n<p>Das Google Data Arts Team hatte sich dazu selbst zwei Aufgaben gestellt: Die L\u00f6sung sollte zum einen intuitiv und zum anderen unendlich skalierbar sein. Das Ergebnis ist ein virtuelles B\u00fccherregal, dessen Design einer 3D-Helixstruktur folgt: eine gigantische Regalschraube, die derzeit \u00fcber 10.000 B\u00fccher im virtuellen Raum fasst.<\/p>\n<p>Die Sammlung ist inhaltlich nach 26 Ressorts sortiert, zwischen denen sich blitzschnell hin- und hernavigieren l\u00e4sst. Die Informationen bez\u00fcglich Autor und Titel sowie die jeweiligen Inhaltsangaben bezieht das System direkt \u00fcber die <a href=\"http:\/\/code.google.com\/apis\/books\/\" target=\"_blank\">Google Books API<\/a>. Wird ein Cover durch den Nutzer angeklickt, wird das Buch aus dem Regal gehoben und mit einem zweiten Klick ge\u00f6ffnet. Hier sehen wir dann die Synopse sowie einen Direktlink zum korrespondieren Eintrag bei Google Books. Auf der linken Seite befindet sich ein QR-Code, mit dessen Hilfe sich die Werke auch schnell auf Smartphones oder Tablets ziehen lassen.<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube-nocookie.com\/embed\/6GqhJDPi-Ug?rel=0&amp;hd=1\" width=\"600\" height=\"335\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Um das <a href=\"http:\/\/www.chromeexperiments.com\/detail\/webgl-bookcase\/\" target=\"_blank\">B\u00fccherregal selbst auszuprobieren<\/a>, wird ein aktueller Browser mit WebGL-Support vorausgesetzt. Mit Google Chrome hat es bei mir direkt auf Anhieb geklappt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ah, sweet innovation! Google l\u00e4sst mal wieder beil\u00e4ufig die Muskeln spielen und pr\u00e4sentierte am Dienstagabend das WebGL Bookcase &#8211; ein neuer Versuch, die Darstellung von B\u00fcchern im Web zeitgem\u00e4\u00dfer zu gestalten. Das Google Data Arts Team hatte sich dazu selbst zwei Aufgaben gestellt: Die L\u00f6sung sollte zum einen intuitiv und zum anderen unendlich skalierbar sein. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_has_post_settings":[],"footnotes":""},"categories":[1,1149],"tags":[1400,1402,1810],"hashtags":[],"class_list":["post-1914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorisiert","category-web-de","tag-google-de","tag-google-books-de","tag-virtuelles-buecherregal"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/1914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/comments?post=1914"}],"version-history":[{"count":0,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/posts\/1914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media\/20786"}],"wp:attachment":[{"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/media?parent=1914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/categories?post=1914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/tags?post=1914"},{"taxonomy":"hashtags","embeddable":true,"href":"https:\/\/www.zbw-mediatalk.eu\/de\/wp-json\/wp\/v2\/hashtags?post=1914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}